{"id":912,"date":"2020-10-23T16:12:27","date_gmt":"2020-10-23T14:12:27","guid":{"rendered":"https:\/\/lordsofverona.promoservicebeta.com\/it\/?post_type=itineraries&#038;p=912"},"modified":"2020-10-26T16:39:15","modified_gmt":"2020-10-26T14:39:15","slug":"verona-romana","status":"publish","type":"itineraries","link":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/","title":{"rendered":"Verona romana"},"content":{"rendered":"<div  class=\"grids-section grids-is-advanced alignfull\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:2\/6;--_ga-row:1\/3;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0px 60px 0px 60px;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0px 60px 0px 60px;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0px 60px 0px 60px;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h1 class=\"wp-block-heading\"><strong>Verona romana<\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Una passeggiata con 2000 anni di storia&nbsp;<strong>fra domus, mosaici, teatri e la magnifica Arena<\/strong>.<\/h2>\n\n\n\n<p>Dai resti di&nbsp;<strong>strade romane degli Scavi Scaligeri<\/strong>&nbsp;proprio di fronte a Lords of Verona, puoi proseguire verso sinistra fino ad arrivare al fiume Adige. L\u00ec troverai il&nbsp;<strong>ponte Pietra<\/strong>, la prima costruzione che i romani realizzarono quando giunsero a Verona.<\/p>\n\n\n\n<p>Sull\u2019altra sponda del fiume potrai ammirare i&nbsp;<strong>resti del Teatro Romano<\/strong>, dove ancora oggi, in estate, si svolgono concerti e rappresentazioni. \u00c8 parte del percorso del museo archeologico di Verona.<\/p>\n\n<\/div>\n\n<div class=\"grids-area image-column-right\" style=\"--_ga-column:6\/13;--_ga-row:1\/2;--_ga-va:center;--_ga-m-desktop:0 0 20px 20px;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 20px - 0);--_ga-m-tablet:0 0 20px 20px;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 20px - 0);--_ga-m-mobile:0 0 20px 20px;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 20px - 0)\">\n\n<figure class=\"wp-block-image size-large image-column-right\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-1024x566.jpg\" alt=\"\" class=\"wp-image-1131\" srcset=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-1024x566.jpg 1024w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-300x166.jpg 300w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-768x424.jpg 768w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-1536x849.jpg 1536w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-1200x663.jpg 1200w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte-1980x1094.jpg 1980w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Ponte.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:6\/11;--_ga-row:3\/5;--_ga-va:flex-end;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 40px 0 40px;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 40px 0 40px;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 40px 0 40px;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Tornando indietro e ripassando per&nbsp;<strong>piazza dei Signori<\/strong>, puoi proseguire poco oltre fino a piazza delle Erbe, il vecchio foro, cio\u00e8 il cuore della vita politica ed economica di ogni citt\u00e0 romana. \u00c8 il centro di Verona da pi\u00f9 di duemila anni.<br>Prendendo via Mazzini, la via dello shopping che parte da piazza delle Erbe, fermati ai negozi Benetton e Kos, e scendi al reparto uomo nel piano interrato. In mezzo ai vestiti troverai&nbsp;<strong>resti di mosaici romani di domus patrizie<\/strong>.<\/p>\n\n\n\n<p>Tornato in superficie prosegui lungo via Mazzini fino a piazza Bra dove c\u2019\u00e8&nbsp;<strong>l\u2019Arena<\/strong>, l\u2019<strong>anfiteatro romano<\/strong>. Un tempo era usato per i combattimenti di gladiatori. Oggi \u00e8 uno dei pi\u00f9 importanti teatri lirici all\u2019aperto del mondo.<br>Girando a destra raggiungerai&nbsp;<strong>porta Borsari<\/strong>, l\u2019ingresso monumentale di Verona di duemila anni fa, ancora incredibilmente ben conservato. Da l\u00ec puoi tornare verso piazza dei Signori e completare il tuo giro nella Verona romana.<\/p>\n\n<\/div>\n\n<div class=\"grids-area image-column-left\" style=\"--_ga-column:1\/6;--_ga-row:3\/5;--_ga-va:flex-end;--_ga-m-desktop:40px 20px 0px 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 20px);--_ga-m-tablet:40px 20px 0px 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 20px);--_ga-m-mobile:40px 20px 0px 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 20px)\">\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div  class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area image-column-left\" style=\"--_ga-column:1\/7;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"757\" height=\"1024\" src=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Arena-757x1024.jpg\" alt=\"\" class=\"wp-image-1103\" srcset=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Arena-757x1024.jpg 757w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Arena-222x300.jpg 222w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Arena-768x1039.jpg 768w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Arena.jpg 798w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area image-column-rounded\" style=\"--_ga-column:8\/13;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"757\" height=\"1024\" src=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Mosaici-757x1024.jpg\" alt=\"\" class=\"wp-image-1106\" srcset=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Mosaici-757x1024.jpg 757w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Mosaici-222x300.jpg 222w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Mosaici-768x1039.jpg 768w, https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/Lord_of_Verona_Luxury_Apartments_Mosaici.jpg 798w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><\/figure>\n\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.<\/p>\n","protected":false},"author":1,"featured_media":913,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-912","itineraries","type-itineraries","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Verona romana - Lords of Verona - Luxury Apartments Verona<\/title>\n<meta name=\"description\" content=\"Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verona romana - Lords of Verona - Luxury Apartments Verona\" \/>\n<meta property=\"og:description\" content=\"Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/\" \/>\n<meta property=\"og:site_name\" content=\"Lords of Verona\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-26T14:39:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/\",\"url\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/\",\"name\":\"Verona romana - Lords of Verona - Luxury Apartments Verona\",\"isPartOf\":{\"@id\":\"https:\/\/www.lordsofverona.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg\",\"datePublished\":\"2020-10-23T14:12:27+00:00\",\"dateModified\":\"2020-10-26T14:39:15+00:00\",\"description\":\"Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#primaryimage\",\"url\":\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg\",\"contentUrl\":\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lordsofverona.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verona romana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lordsofverona.it\/it\/#website\",\"url\":\"https:\/\/www.lordsofverona.it\/it\/\",\"name\":\"Lords of Verona\",\"description\":\"Luxury Apartments Verona\",\"publisher\":{\"@id\":\"https:\/\/www.lordsofverona.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lordsofverona.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lordsofverona.it\/it\/#organization\",\"name\":\"Lords of Verona\",\"url\":\"https:\/\/www.lordsofverona.it\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lordsofverona.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/logo.png\",\"width\":800,\"height\":63,\"caption\":\"Lords of Verona\"},\"image\":{\"@id\":\"https:\/\/www.lordsofverona.it\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verona romana - Lords of Verona - Luxury Apartments Verona","description":"Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/","og_locale":"it_IT","og_type":"article","og_title":"Verona romana - Lords of Verona - Luxury Apartments Verona","og_description":"Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.","og_url":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/","og_site_name":"Lords of Verona","article_modified_time":"2020-10-26T14:39:15+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/","url":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/","name":"Verona romana - Lords of Verona - Luxury Apartments Verona","isPartOf":{"@id":"https:\/\/www.lordsofverona.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#primaryimage"},"image":{"@id":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg","datePublished":"2020-10-23T14:12:27+00:00","dateModified":"2020-10-26T14:39:15+00:00","description":"Una passeggiata con 2000 anni di storia fra domus, mosaici, teatri e la magnifica Arena.","breadcrumb":{"@id":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#primaryimage","url":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg","contentUrl":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.lordsofverona.it\/it\/itinerari\/verona-romana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lordsofverona.it\/it\/"},{"@type":"ListItem","position":2,"name":"Verona romana"}]},{"@type":"WebSite","@id":"https:\/\/www.lordsofverona.it\/it\/#website","url":"https:\/\/www.lordsofverona.it\/it\/","name":"Lords of Verona","description":"Luxury Apartments Verona","publisher":{"@id":"https:\/\/www.lordsofverona.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lordsofverona.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.lordsofverona.it\/it\/#organization","name":"Lords of Verona","url":"https:\/\/www.lordsofverona.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lordsofverona.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/logo.png","width":800,"height":63,"caption":"Lords of Verona"},"image":{"@id":"https:\/\/www.lordsofverona.it\/it\/#\/schema\/logo\/image\/"}}]}},"featured_img":"https:\/\/www.lordsofverona.it\/wp-content\/uploads\/2020\/10\/arena-di-verona_notturno-1200x900.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/www.lordsofverona.it\/it\/author\/l0rds_sostl3qg\/","display_name":"admin"},"relative_dates":{"created":"Pubblicato 6 anni fa","modified":"Aggiornato 6 anni fa"},"absolute_dates":{"created":"Pubblicato il 10\/23\/2020","modified":"Aggiornato il 10\/26\/2020"},"absolute_dates_time":{"created":"Pubblicato il 10\/23\/2020 16:12","modified":"Aggiornato il 10\/26\/2020 16:39"},"featured_img_caption":"","tax_additional":{"translation_priority":{"linked":[],"unlinked":[],"slug":"translation_priority","name":"Priorit\u00e0 di Traduzione"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/itineraries\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/itineraries"}],"about":[{"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/types\/itineraries"}],"author":[{"embeddable":true,"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/itineraries\/912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/media\/913"}],"wp:attachment":[{"href":"https:\/\/www.lordsofverona.it\/it\/wp-json\/wp\/v2\/media?parent=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}